{"id":33,"date":"2016-07-27T17:54:41","date_gmt":"2016-07-27T17:54:41","guid":{"rendered":"http:\/\/kapush.org\/portfolio\/?page_id=33"},"modified":"2016-07-31T13:13:20","modified_gmt":"2016-07-31T13:13:20","slug":"kapushfolio","status":"publish","type":"page","link":"https:\/\/kapush.org\/portfolio\/","title":{"rendered":"KapushFolio"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-33","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KapushFolio - KapushFolio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kapush.org\/portfolio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KapushFolio - KapushFolio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kapush.org\/portfolio\/\" \/>\n<meta property=\"og:site_name\" content=\"KapushFolio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arindam.dasgupta.73\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-31T13:13:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@kapushdotnet\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kapush.org\\\/portfolio\\\/\",\"url\":\"https:\\\/\\\/kapush.org\\\/portfolio\\\/\",\"name\":\"KapushFolio - KapushFolio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kapush.org\\\/portfolio\\\/#website\"},\"datePublished\":\"2016-07-27T17:54:41+00:00\",\"dateModified\":\"2016-07-31T13:13:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kapush.org\\\/portfolio\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kapush.org\\\/portfolio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kapush.org\\\/portfolio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kapush.org\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KapushFolio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kapush.org\\\/portfolio\\\/#website\",\"url\":\"https:\\\/\\\/kapush.org\\\/portfolio\\\/\",\"name\":\"KapushFolio\",\"description\":\"Word &amp; Art\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kapush.org\\\/portfolio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KapushFolio - KapushFolio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kapush.org\/portfolio\/","og_locale":"en_US","og_type":"article","og_title":"KapushFolio - KapushFolio","og_url":"https:\/\/kapush.org\/portfolio\/","og_site_name":"KapushFolio","article_publisher":"https:\/\/www.facebook.com\/arindam.dasgupta.73","article_modified_time":"2016-07-31T13:13:20+00:00","twitter_card":"summary_large_image","twitter_site":"@kapushdotnet","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kapush.org\/portfolio\/","url":"https:\/\/kapush.org\/portfolio\/","name":"KapushFolio - KapushFolio","isPartOf":{"@id":"https:\/\/kapush.org\/portfolio\/#website"},"datePublished":"2016-07-27T17:54:41+00:00","dateModified":"2016-07-31T13:13:20+00:00","breadcrumb":{"@id":"https:\/\/kapush.org\/portfolio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kapush.org\/portfolio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kapush.org\/portfolio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kapush.org\/portfolio\/"},{"@type":"ListItem","position":2,"name":"KapushFolio"}]},{"@type":"WebSite","@id":"https:\/\/kapush.org\/portfolio\/#website","url":"https:\/\/kapush.org\/portfolio\/","name":"KapushFolio","description":"Word &amp; Art","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kapush.org\/portfolio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/kapush.org\/portfolio\/wp-json\/wp\/v2\/pages\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kapush.org\/portfolio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kapush.org\/portfolio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kapush.org\/portfolio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kapush.org\/portfolio\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":5,"href":"https:\/\/kapush.org\/portfolio\/wp-json\/wp\/v2\/pages\/33\/revisions"}],"predecessor-version":[{"id":235,"href":"https:\/\/kapush.org\/portfolio\/wp-json\/wp\/v2\/pages\/33\/revisions\/235"}],"wp:attachment":[{"href":"https:\/\/kapush.org\/portfolio\/wp-json\/wp\/v2\/media?parent=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}